{"id":5537,"count":1,"description":"","link":"https:\/\/radioleinewelle.de\/index.php\/tag\/vinylderwoche\/","name":"#VinylDerWoche","slug":"vinylderwoche","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>#VinylDerWoche Archive - Radio Leinewelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioleinewelle.de\/index.php\/tag\/vinylderwoche\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#VinylDerWoche Archive - Radio Leinewelle\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioleinewelle.de\/index.php\/tag\/vinylderwoche\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Leinewelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@RLeinewelle\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/radioleinewelle.de\\\/index.php\\\/tag\\\/vinylderwoche\\\/\",\"url\":\"https:\\\/\\\/radioleinewelle.de\\\/index.php\\\/tag\\\/vinylderwoche\\\/\",\"name\":\"#VinylDerWoche Archive - Radio Leinewelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioleinewelle.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioleinewelle.de\\\/index.php\\\/tag\\\/vinylderwoche\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioleinewelle.de\\\/index.php\\\/tag\\\/vinylderwoche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/radioleinewelle.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#VinylDerWoche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioleinewelle.de\\\/#website\",\"url\":\"https:\\\/\\\/radioleinewelle.de\\\/\",\"name\":\"Radio Leinewelle\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioleinewelle.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radioleinewelle.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioleinewelle.de\\\/#organization\",\"name\":\"Radio Leinewelle\",\"alternateName\":\"Mein Radio f\u00fcr S\u00fcdniedersachsen\",\"url\":\"https:\\\/\\\/radioleinewelle.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/radioleinewelle.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radioleinewelle.de\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-Leinewelle_Logo_weiss.png\",\"contentUrl\":\"https:\\\/\\\/radioleinewelle.de\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-Leinewelle_Logo_weiss.png\",\"width\":854,\"height\":260,\"caption\":\"Radio Leinewelle\"},\"image\":{\"@id\":\"https:\\\/\\\/radioleinewelle.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/radioleinewelle\",\"https:\\\/\\\/x.com\\\/RLeinewelle\",\"https:\\\/\\\/www.instagram.com\\\/radioleinewelle\\\/?hl=de\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#VinylDerWoche Archive - Radio Leinewelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioleinewelle.de\/index.php\/tag\/vinylderwoche\/","og_locale":"de_DE","og_type":"article","og_title":"#VinylDerWoche Archive - Radio Leinewelle","og_url":"https:\/\/radioleinewelle.de\/index.php\/tag\/vinylderwoche\/","og_site_name":"Radio Leinewelle","twitter_card":"summary_large_image","twitter_site":"@RLeinewelle","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/radioleinewelle.de\/index.php\/tag\/vinylderwoche\/","url":"https:\/\/radioleinewelle.de\/index.php\/tag\/vinylderwoche\/","name":"#VinylDerWoche Archive - Radio Leinewelle","isPartOf":{"@id":"https:\/\/radioleinewelle.de\/#website"},"breadcrumb":{"@id":"https:\/\/radioleinewelle.de\/index.php\/tag\/vinylderwoche\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/radioleinewelle.de\/index.php\/tag\/vinylderwoche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/radioleinewelle.de\/"},{"@type":"ListItem","position":2,"name":"#VinylDerWoche"}]},{"@type":"WebSite","@id":"https:\/\/radioleinewelle.de\/#website","url":"https:\/\/radioleinewelle.de\/","name":"Radio Leinewelle","description":"","publisher":{"@id":"https:\/\/radioleinewelle.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioleinewelle.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/radioleinewelle.de\/#organization","name":"Radio Leinewelle","alternateName":"Mein Radio f\u00fcr S\u00fcdniedersachsen","url":"https:\/\/radioleinewelle.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/radioleinewelle.de\/#\/schema\/logo\/image\/","url":"https:\/\/radioleinewelle.de\/wp-content\/uploads\/2023\/11\/cropped-Leinewelle_Logo_weiss.png","contentUrl":"https:\/\/radioleinewelle.de\/wp-content\/uploads\/2023\/11\/cropped-Leinewelle_Logo_weiss.png","width":854,"height":260,"caption":"Radio Leinewelle"},"image":{"@id":"https:\/\/radioleinewelle.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radioleinewelle","https:\/\/x.com\/RLeinewelle","https:\/\/www.instagram.com\/radioleinewelle\/?hl=de"]}]}},"_links":{"self":[{"href":"https:\/\/radioleinewelle.de\/index.php\/wp-json\/wp\/v2\/tags\/5537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioleinewelle.de\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/radioleinewelle.de\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/radioleinewelle.de\/index.php\/wp-json\/wp\/v2\/posts?tags=5537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}